{"id":393,"date":"2025-02-27T11:54:37","date_gmt":"2025-02-27T11:54:37","guid":{"rendered":"https:\/\/yeditepearitma.com\/en\/?post_type=portfolio&#038;p=393"},"modified":"2025-03-25T23:53:08","modified_gmt":"2025-03-25T23:53:08","slug":"bogazkoy-village","status":"publish","type":"portfolio","link":"https:\/\/yeditepearitma.com\/en\/referanslar\/bogazkoy-village\/","title":{"rendered":"Bo\u011fazk\u00f6y Village"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":304,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"portfolio-types":[5],"class_list":["post-393","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-types-domestic-wastewater"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"yunusemre\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/yeditepearitma.com\/en\/referanslar\/bogazkoy-village\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"tr_TR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Yeditepe Treatment -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Bo\u011fazk\u00f6y Village - Yeditepe Treatment\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/yeditepearitma.com\/en\/referanslar\/bogazkoy-village\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-02-27T11:54:37+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-03-25T23:53:08+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Bo\u011fazk\u00f6y Village - Yeditepe Treatment\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/referanslar\\\/bogazkoy-village\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/yeditepearitma.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/portfolio-types\\\/domestic-wastewater\\\/#listItem\",\"name\":\"Domestic Wastewater\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/portfolio-types\\\/domestic-wastewater\\\/#listItem\",\"position\":2,\"name\":\"Domestic Wastewater\",\"item\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/portfolio-types\\\/domestic-wastewater\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/referanslar\\\/bogazkoy-village\\\/#listItem\",\"name\":\"Bo\\u011fazk\\u00f6y Village\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/referanslar\\\/bogazkoy-village\\\/#listItem\",\"position\":3,\"name\":\"Bo\\u011fazk\\u00f6y Village\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/portfolio-types\\\/domestic-wastewater\\\/#listItem\",\"name\":\"Domestic Wastewater\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/#organization\",\"name\":\"Yeditepe Treatment\",\"url\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/\",\"telephone\":\"+902165732090\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Yeditepe-Logo-EN.png\",\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/referanslar\\\/bogazkoy-village\\\/#organizationLogo\",\"width\":1841,\"height\":526},\"image\":{\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/referanslar\\\/bogazkoy-village\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/author\\\/yunusemre\\\/#author\",\"url\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/author\\\/yunusemre\\\/\",\"name\":\"yunusemre\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/referanslar\\\/bogazkoy-village\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de181f73e1f1fc42a01e82d80c067ce2?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"yunusemre\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/referanslar\\\/bogazkoy-village\\\/#webpage\",\"url\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/referanslar\\\/bogazkoy-village\\\/\",\"name\":\"Bo\\u011fazk\\u00f6y Village - Yeditepe Treatment\",\"inLanguage\":\"tr-TR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/referanslar\\\/bogazkoy-village\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/author\\\/yunusemre\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/author\\\/yunusemre\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Referanslar-Yeditepe-Aritim.jpg\",\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/referanslar\\\/bogazkoy-village\\\/#mainImage\",\"width\":1080,\"height\":1080},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/referanslar\\\/bogazkoy-village\\\/#mainImage\"},\"datePublished\":\"2025-02-27T11:54:37+00:00\",\"dateModified\":\"2025-03-25T23:53:08+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/\",\"name\":\"Yeditepe Treatment - Yeditepe Ar\\u0131t\\u0131m\",\"inLanguage\":\"tr-TR\",\"publisher\":{\"@id\":\"https:\\\/\\\/yeditepearitma.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Bo\u011fazk\u00f6y Village - Yeditepe Treatment","description":"","canonical_url":"https:\/\/yeditepearitma.com\/en\/referanslar\/bogazkoy-village\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/yeditepearitma.com\/en\/referanslar\/bogazkoy-village\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/yeditepearitma.com\/en#listItem","position":1,"name":"Home","item":"https:\/\/yeditepearitma.com\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/yeditepearitma.com\/en\/portfolio-types\/domestic-wastewater\/#listItem","name":"Domestic Wastewater"}},{"@type":"ListItem","@id":"https:\/\/yeditepearitma.com\/en\/portfolio-types\/domestic-wastewater\/#listItem","position":2,"name":"Domestic Wastewater","item":"https:\/\/yeditepearitma.com\/en\/portfolio-types\/domestic-wastewater\/","nextItem":{"@type":"ListItem","@id":"https:\/\/yeditepearitma.com\/en\/referanslar\/bogazkoy-village\/#listItem","name":"Bo\u011fazk\u00f6y Village"},"previousItem":{"@type":"ListItem","@id":"https:\/\/yeditepearitma.com\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/yeditepearitma.com\/en\/referanslar\/bogazkoy-village\/#listItem","position":3,"name":"Bo\u011fazk\u00f6y Village","previousItem":{"@type":"ListItem","@id":"https:\/\/yeditepearitma.com\/en\/portfolio-types\/domestic-wastewater\/#listItem","name":"Domestic Wastewater"}}]},{"@type":"Organization","@id":"https:\/\/yeditepearitma.com\/en\/#organization","name":"Yeditepe Treatment","url":"https:\/\/yeditepearitma.com\/en\/","telephone":"+902165732090","logo":{"@type":"ImageObject","url":"https:\/\/yeditepearitma.com\/en\/wp-content\/uploads\/2025\/03\/Yeditepe-Logo-EN.png","@id":"https:\/\/yeditepearitma.com\/en\/referanslar\/bogazkoy-village\/#organizationLogo","width":1841,"height":526},"image":{"@id":"https:\/\/yeditepearitma.com\/en\/referanslar\/bogazkoy-village\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/yeditepearitma.com\/en\/author\/yunusemre\/#author","url":"https:\/\/yeditepearitma.com\/en\/author\/yunusemre\/","name":"yunusemre","image":{"@type":"ImageObject","@id":"https:\/\/yeditepearitma.com\/en\/referanslar\/bogazkoy-village\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/de181f73e1f1fc42a01e82d80c067ce2?s=96&d=mm&r=g","width":96,"height":96,"caption":"yunusemre"}},{"@type":"WebPage","@id":"https:\/\/yeditepearitma.com\/en\/referanslar\/bogazkoy-village\/#webpage","url":"https:\/\/yeditepearitma.com\/en\/referanslar\/bogazkoy-village\/","name":"Bo\u011fazk\u00f6y Village - Yeditepe Treatment","inLanguage":"tr-TR","isPartOf":{"@id":"https:\/\/yeditepearitma.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/yeditepearitma.com\/en\/referanslar\/bogazkoy-village\/#breadcrumblist"},"author":{"@id":"https:\/\/yeditepearitma.com\/en\/author\/yunusemre\/#author"},"creator":{"@id":"https:\/\/yeditepearitma.com\/en\/author\/yunusemre\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/yeditepearitma.com\/en\/wp-content\/uploads\/2025\/02\/Referanslar-Yeditepe-Aritim.jpg","@id":"https:\/\/yeditepearitma.com\/en\/referanslar\/bogazkoy-village\/#mainImage","width":1080,"height":1080},"primaryImageOfPage":{"@id":"https:\/\/yeditepearitma.com\/en\/referanslar\/bogazkoy-village\/#mainImage"},"datePublished":"2025-02-27T11:54:37+00:00","dateModified":"2025-03-25T23:53:08+00:00"},{"@type":"WebSite","@id":"https:\/\/yeditepearitma.com\/en\/#website","url":"https:\/\/yeditepearitma.com\/en\/","name":"Yeditepe Treatment - Yeditepe Ar\u0131t\u0131m","inLanguage":"tr-TR","publisher":{"@id":"https:\/\/yeditepearitma.com\/en\/#organization"}}]},"og:locale":"tr_TR","og:site_name":"Yeditepe Treatment -","og:type":"article","og:title":"Bo\u011fazk\u00f6y Village - Yeditepe Treatment","og:url":"https:\/\/yeditepearitma.com\/en\/referanslar\/bogazkoy-village\/","article:published_time":"2025-02-27T11:54:37+00:00","article:modified_time":"2025-03-25T23:53:08+00:00","twitter:card":"summary_large_image","twitter:title":"Bo\u011fazk\u00f6y Village - Yeditepe Treatment"},"aioseo_meta_data":{"post_id":"393","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-03-19 19:05:42","updated":"2025-06-05 07:56:35","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/yeditepearitma.com\/en\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/yeditepearitma.com\/en\/portfolio-types\/domestic-wastewater\/\" title=\"Domestic Wastewater\">Domestic Wastewater<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tBo\u011fazk\u00f6y Village\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/yeditepearitma.com\/en"},{"label":"Domestic Wastewater","link":"https:\/\/yeditepearitma.com\/en\/portfolio-types\/domestic-wastewater\/"},{"label":"Bo\u011fazk\u00f6y Village","link":"https:\/\/yeditepearitma.com\/en\/referanslar\/bogazkoy-village\/"}],"_links":{"self":[{"href":"https:\/\/yeditepearitma.com\/en\/wp-json\/wp\/v2\/portfolio\/393","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yeditepearitma.com\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/yeditepearitma.com\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/yeditepearitma.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/yeditepearitma.com\/en\/wp-json\/wp\/v2\/comments?post=393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yeditepearitma.com\/en\/wp-json\/wp\/v2\/media\/304"}],"wp:attachment":[{"href":"https:\/\/yeditepearitma.com\/en\/wp-json\/wp\/v2\/media?parent=393"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/yeditepearitma.com\/en\/wp-json\/wp\/v2\/portfolio-types?post=393"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}